{"id":14369,"date":"2015-12-16T00:00:00","date_gmt":"2015-12-16T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/"},"modified":"2025-10-30T12:39:24","modified_gmt":"2025-10-30T12:39:24","slug":"el-nacimiento-de-rhodon","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/el-nacimiento-de-rhodon\/","title":{"rendered":"El nacimiento de Rhodon"},"content":{"rendered":"<p>Seg\u00fan la mitolog\u00eda griega la rosa naci\u00f3 cuando <em>Chloris<\/em>, diosa de las flores, tropez\u00f3 con el cuerpo sin vida de una bella ninfa tumbada en el bosque. Movida por su destino, <em>Chloris<\/em> mir\u00f3 a sus compa\u00f1eros dioses en busca de ayuda y transformaron a la ninfa en una flor, una rosa.<\/p>\n<p>\u00a0<\/p>\n<p>Esta historia es la que se ve reflejada en la pieza Rhodon, del griego antiguo \u201cla rosa\u201d. Se trata de un lavabo de porcelana natural pintado a mano en el Bathco Atelier que \u00a0transmite la elegancia y naturalidad de los motivos y colores de las antiguas cer\u00e1micas, pero esta vez con aire renovado a trav\u00e9s de sus l\u00edneas ligeras, sencillas y finas. La atemporalidad es la principal caracter\u00edstica de la pieza que teje v\u00ednculos entre tradici\u00f3n y modernidad.<\/p>","protected":false},"featured_media":14370,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14369","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El nacimiento de Rhodon - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/el-nacimiento-de-rhodon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nacimiento de Rhodon - Bathco\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan la mitolog\u00eda griega la rosa naci\u00f3 cuando Chloris, diosa de las flores, tropez\u00f3 con el cuerpo sin vida de una bella ninfa tumbada en el bosque. Movida por su destino, Chloris mir\u00f3 a sus compa\u00f1eros dioses en busca de ayuda y transformaron a la ninfa en una flor, una rosa. \u00a0 Esta historia es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/el-nacimiento-de-rhodon\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/\",\"name\":\"El nacimiento de Rhodon - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png\",\"datePublished\":\"2015-12-16T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png\",\"width\":2560,\"height\":1590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/el-nacimiento-de-rhodon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El nacimiento de Rhodon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nacimiento de Rhodon - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/el-nacimiento-de-rhodon\/","og_locale":"en_US","og_type":"article","og_title":"El nacimiento de Rhodon - Bathco","og_description":"Seg\u00fan la mitolog\u00eda griega la rosa naci\u00f3 cuando Chloris, diosa de las flores, tropez\u00f3 con el cuerpo sin vida de una bella ninfa tumbada en el bosque. Movida por su destino, Chloris mir\u00f3 a sus compa\u00f1eros dioses en busca de ayuda y transformaron a la ninfa en una flor, una rosa. \u00a0 Esta historia es [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/el-nacimiento-de-rhodon\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:24+00:00","og_image":[{"width":2560,"height":1590,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/","url":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/","name":"El nacimiento de Rhodon - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png","datePublished":"2015-12-16T00:00:00+00:00","dateModified":"2025-10-30T12:39:24+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12660_es-rhodon-l-bathco-atelier-l-the-bath-collection-Real-scaled.png","width":2560,"height":1590},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/el-nacimiento-de-rhodon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"El nacimiento de Rhodon"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14370"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14369"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}