{"id":14374,"date":"2015-12-21T00:00:00","date_gmt":"2015-12-21T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/"},"modified":"2025-10-30T12:39:24","modified_gmt":"2025-10-30T12:39:24","slug":"recordamos-2015-para-afrontar-2016","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/recordamos-2015-para-afrontar-2016\/","title":{"rendered":"Recordamos 2015 para afrontar 2016"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\">En enero hicimos las maletas con la misma ilusi\u00f3n que tenemos a d\u00eda de hoy tras ver que lo prometido hace un a\u00f1o se ha cumplido: seguir sorprendiendo con nuestras novedades.<\/p>\n<p style=\"text-align: left;\" align=\"center\">Hace doce meses nos preparamos para viajar a Las Vegas para participar por primera vez en <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/kbis-has-another-banner-year.html\/\">KBIS<\/a><\/strong> donde presentamos los productos m\u00e1s innovadores de las colecciones Natural Series by Bathco.<\/p>\n<p style=\"text-align: left;\" align=\"center\">En febrero nos fuimos a Valencia para estar presentes en <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/bathco-presenta-sus-novedades-en-cevisama-2015.html\/\">CEVISAMA<\/a><\/strong> donde tuvimos una gran acogida, como siempre, estar en esta feria es como estar en casa. Fue aqu\u00ed donde las colecciones de <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/bathco-by-david-delfin\/\">David Delf\u00edn<\/a><\/strong> and <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/bathco-by-mariscal\/\">Javier Mariscal<\/a>\u00a0<\/strong>vieron la luz por primera vez y mostramos la ampliaci\u00f3n de decorados de la Colecci\u00f3n <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/vintage\/\">Vintage<\/a><\/strong>.<\/p>\n<p style=\"text-align: left;\" align=\"center\">De ah\u00ed volamos a Frankfurt en marzo para participar en <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/bathco-presente-en-ish-2015.html\/\">ISH<\/a><\/strong>. All\u00ed, adem\u00e1s de las novedades anteriores, los visitantes pudieron conocer el \u00faltimo cat\u00e1logo que Bathco dise\u00f1a para el sector de la reforma y la construcci\u00f3n: PROJECTS. Este cat\u00e1logo nos abri\u00f3 las puertas a grandes proyectos como el nuevo hotel Hilton en M\u00e1laga o la nueva fase del Hospital Valdecilla en Santander.<\/p>\n<p style=\"text-align: left;\" align=\"center\">Mayo fue un mes muy especial para nosotros porque inauguramos el<strong> <a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/atelier\/\">Bathco Atelier<\/a><\/strong>, un espacio pensado para la investigaci\u00f3n de nuevos materiales y el dise\u00f1o y desarrollo de piezas de ba\u00f1o que ofrecen nuevas posibilidades a los clientes.<\/p>\n<p style=\"text-align: left;\" align=\"center\">Sin terminar apenas el brindis de la celebraci\u00f3n volamos a Bogot\u00e1 y, m\u00e1s concretamente, a <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/bathco-expoconstruccion-expodiseno-bogota.html\/\">Expoconstrucci\u00f3n Expodise\u00f1o<\/a><\/strong>, el mayor escenario de promoci\u00f3n para el sector de la construcci\u00f3n en el continente latinoamericano.<\/p>\n<p>La apuesta por el mundo del arte a trav\u00e9s del Bathco Atelier nos llev\u00f3 en julio a <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/los-lavabos-de-bathco-se-hacen-un-hueco-en-arte-santander.html\/\">ArteSantander<\/a><\/strong>, la feria de arte de referencia del norte de Espa\u00f1a.<\/p>\n<p>En septiembre el dise\u00f1o nos esperaba cerca de casa, en Bolonia (Italia), en la feria <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/bathco-impulsa-el-sector-del-bano-en-cersaie-2015.html\/\">CERSAIE<\/a><\/strong>. Fue aqu\u00ed donde las obras de Bathco Atelier se presentaron en exclusiva para todo el mundo.<\/p>\n<p>Latinoam\u00e9rica nos recibi\u00f3 de nuevo en octubre pero esta vez en M\u00e9xico para estar presentes en <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/cantabria-unica-ccaa-presente-en-la-expocihac-mexico-df.html\/\">EXPOCIHAC<\/a><\/strong> representando a Cantabria, la \u00fanica comunidad aut\u00f3noma que particip\u00f3 en esta feria con m\u00e1s de 500 expositores de la industria de la construcci\u00f3n en M\u00e9xico.<\/p>\n<p>El 30 de octubre quisimos quedarnos en nuestra casa, en Santander, para presentar las reproducciones de los ba\u00f1os de primera y segunda clase del <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/santander-presencia-la-el-descubrimiento-de-los-banos-del-titanic.html\/\">Titanic<\/a><\/strong>; un proyecto muy ambicioso que ya ha comenzado su producci\u00f3n para preservar la historia del buque de los sue\u00f1os.<\/p>\n<p>Del fr\u00edo del iceberg nos fuimos al calor del desierto para participar en <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/bathco-se-prepara-en-the-big-5.html\/\">Big 5<\/a><\/strong> en noviembre, la mayor feria de construcci\u00f3n e ingenier\u00eda civil de Oriente Medio. El brillo y el color destacaron en Dub\u00e1i con las nuevas colecciones <a href=\"http:\/\/www.youblisher.com\/p\/1281991-Gold-and-Silver\/\" target=\"_blank\"><strong>Gold&amp;Silver<\/strong><\/a> and <strong>Bicolor<\/strong>.<\/p>\n<p>Como broche final del a\u00f1o, una cita con el arte nos esperaba; <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/noticias\/bathco-atelier-estara-presente-en-art-basel-miami-beach.html\/\">ArtBasel<\/a><\/strong>, la medi\u00e1tica feria de arte celebrada en Miami Beach fue testigo de las obras de Bathco Atelier.<\/p>\n<p>A pesar de todas las novedades, no han perdido protagonismo las piezas de <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/fltr\/material-porcelana\/\">porcelain<\/a><\/strong> and <strong>Natural Series<\/strong> en la que se incluye las diferentes colecciones de <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/fltr\/material-piedra\/\">Stone Series<\/a><\/strong>, <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/fltr\/material-cemento%20&amp;%20terrazo\/\">Cemento y Terrazo<\/a><\/strong> and<strong> <a href=\"https:\/\/www.thebathcollection.com\/en\/producto\/fltr\/material-solid%20surface\/\">Solid Surface<\/a><\/strong>. Estas piezas ya forman parte de nuestro ADN y nos acompa\u00f1an all\u00e1 donde vamos.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\" align=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/f_ZtgTCuAvE\" frameborder=\"0\" width=\"780\" height=\"439\"><\/iframe><\/p>\n<p><strong>Patrocinios<\/strong><\/p>\n<p>Por supuesto, nuestra <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/the-bath-collection\/responsabilidad-social\/\">Responsabilidad Social Corporativa<\/a><\/strong> nos ha llevado a continuar con patrocinios deportivos apoyando al <strong>Bathco Rugby Club<\/strong>, <strong>Clio Raid Marrakech<\/strong>, <strong>Club Ciclista Besaya<\/strong>, <strong>Paula Gonz\u00e1lez Berodia<\/strong>, <strong>Triatl\u00f3n Valle de Buelna<\/strong> and the <strong>I Torneo de P\u00e1del<\/strong> organizado por El Diario Monta\u00f1\u00e9s.<\/p>\n<p>A eso se suma la apuesta por las generaciones futuras, este a\u00f1o hemos iniciado la mentorizaci\u00f3n del centro San Juan Bautista de Los Corrales de Buelna a trav\u00e9s del programa <strong>StartInnova<\/strong> con el fin de crear futuros emprendedores.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Presencia online<\/strong><\/p>\n<p>2015 ha sido un a\u00f1o 2.0 para Bathco, gracias a ello la interactividad con clientes y seguidores ha sido muy gratificante. Nuestros seguidores en <strong><a href=\"https:\/\/www.facebook.com\/bathco\" target=\"_blank\">Facebook<\/a><\/strong> han aumentado en un 53,65%, el n\u00famero de seguidores en <strong><a href=\"https:\/\/twitter.com\/bathcollection\" target=\"_blank\">Twitter<\/a><\/strong> se ha incrementado en un 76,22% y nuestra p\u00e1gina de <strong><a href=\"https:\/\/www.linkedin.com\/company\/3164674?trk=tyah&amp;trkInfo=clickedVertical%3Acompany%2CclickedEntityId%3A3164674%2Cidx%3A2-1-2%2CtarId%3A1448961100229%2Ctas%3Abathco\" target=\"_blank\">LinkedIn<\/a><\/strong> en un 50,39%. Respecto a las redes m\u00e1s visuales, hemos continuado con nuestra presencia en <strong><a href=\"https:\/\/www.pinterest.com\/bathco\/\" target=\"_blank\">Pinterest<\/a><\/strong> alcanzando los 518 pines y nuestros v\u00eddeos han sido vistos por m\u00e1s de\u00a078.000 usuarios. En septiembre decidimos estrenar nuestra cuenta de <strong><a href=\"https:\/\/www.instagram.com\/bathco\/\" target=\"_blank\">Instagram<\/a><\/strong> que va creciendo d\u00eda a d\u00eda y hoy cuenta con 164 fans.<\/p>\n<p>En junio estrenamos la nueva p\u00e1gina <strong><a href=\"https:\/\/www.thebathcollection.com\/en\/\" target=\"_blank\">web<\/a><\/strong>, esto ha favorecido el aumento de visitantes en diferentes dispositivos y ha motivado una mejora en el posicionamiento. Como consecuencia, nuestros productos han estado presentes en blogs, webs y publicaciones de referencia \u00a0del sector recibiendo la confianza de nuestros lectores y anim\u00e1ndonos a mejorar los contenidos, aspectos est\u00e9ticos y t\u00e9cnicos en los que seguimos trabajando d\u00eda a d\u00eda. En concreto, contamos con \u00a066.600 usuarios \u00fanicos y m\u00e1s de 793.000 p\u00e1ginas vistas.<\/p>\n<p>En definitiva, estamos orgullosos por el trabajo realizado y agradecidos a todos nuestros clientes que siguen confiando en nosotros. Esta confianza nos permite seguir investigando en nuevos materiales que se traducen en todas las novedades que presentamos feria tras feria.<\/p>","protected":false},"featured_media":14375,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14374","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recordamos 2015 para afrontar 2016 - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/recordamos-2015-para-afrontar-2016\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recordamos 2015 para afrontar 2016 - Bathco\" \/>\n<meta property=\"og:description\" content=\"En enero hicimos las maletas con la misma ilusi\u00f3n que tenemos a d\u00eda de hoy tras ver que lo prometido hace un a\u00f1o se ha cumplido: seguir sorprendiendo con nuestras novedades. Hace doce meses nos preparamos para viajar a Las Vegas para participar por primera vez en KBIS donde presentamos los productos m\u00e1s innovadores de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/recordamos-2015-para-afrontar-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"302\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/\",\"name\":\"Recordamos 2015 para afrontar 2016 - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png\",\"datePublished\":\"2015-12-21T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png\",\"width\":390,\"height\":302},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/recordamos-2015-para-afrontar-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recordamos 2015 para afrontar 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recordamos 2015 para afrontar 2016 - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/recordamos-2015-para-afrontar-2016\/","og_locale":"en_US","og_type":"article","og_title":"Recordamos 2015 para afrontar 2016 - Bathco","og_description":"En enero hicimos las maletas con la misma ilusi\u00f3n que tenemos a d\u00eda de hoy tras ver que lo prometido hace un a\u00f1o se ha cumplido: seguir sorprendiendo con nuestras novedades. Hace doce meses nos preparamos para viajar a Las Vegas para participar por primera vez en KBIS donde presentamos los productos m\u00e1s innovadores de [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/recordamos-2015-para-afrontar-2016\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:24+00:00","og_image":[{"width":390,"height":302,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/","url":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/","name":"Recordamos 2015 para afrontar 2016 - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png","datePublished":"2015-12-21T00:00:00+00:00","dateModified":"2025-10-30T12:39:24+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12847_es-feliz-navidad-the-bath-collection-bathco-Real.png","width":390,"height":302},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/recordamos-2015-para-afrontar-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Recordamos 2015 para afrontar 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14375"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14374"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}