{"id":14385,"date":"2016-01-18T00:00:00","date_gmt":"2016-01-18T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/"},"modified":"2025-10-30T12:39:25","modified_gmt":"2025-10-30T12:39:25","slug":"cevisama-2016-mucho-mas-que-una-feria-comercial","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/","title":{"rendered":"Cevisama 2016, mucho m\u00e1s que una feria comercial"},"content":{"rendered":"<p><span class=\"Fuente\"><span class=\"Negrita\">J. CABRERIZO<\/span>\u00a0\/\u00a0<a title=\"El Peri\u00f3dico del azulejo\" href=\"http:\/\/www.elperiodicodelazulejo.es\/noticias\/actualidad\/cevisama-2016-mucho-mas-feria-comercial_2393.html\" target=\"_blank\">El Peri\u00f3dico del Azulejo<\/a><\/span><\/p>\n<div id=\"CuerpoDeLaNoticia\">\n<p>Cevisama es, ante todo, una feria comercial al uso, pero en los \u00faltimos a\u00f1os el certamen est\u00e1 incorporando a su oferta numerosos eventos complementarios, algo que se va a potenciar todav\u00eda m\u00e1s en su edici\u00f3n 2016, que se celebrar\u00e1\u00a0<strong>del 1 al 5 de febrero en Valencia<\/strong>.<\/p>\n<p>El certamen aglutinar\u00e1 a m\u00e1s de 700 marcas de cer\u00e1mica, esmaltes, maquinaria (como todos los a\u00f1os pares), ba\u00f1o y cocina, suficientes alicientes para asegurar un flujo importante de asistentes. La simultaneidad en fechas y recinto con H\u00e1bitat Valencia (el sal\u00f3n del mueble) y Fimma-Maderalia (suelos, puertas, ventanas y tecnolog\u00eda vinculada a la madera) depara una macroferia que cada a\u00f1o visitan m\u00e1s profesionales.<\/p>\n<p>A ello, la organizaci\u00f3n de la cita ha agregado un completo programa paralelo de actividades, enmarcadas en los ciclos Nos vemos en Valencia y Cevisama Lab, que buscan dotar de m\u00e1s \u2018contenido\u2019 a la convocatoria. La aspiraci\u00f3n es lograr que la asistencia de profesionales del dise\u00f1o, la arquitectura y el interiorismo sea de m\u00e1s cantidad y calidad.<\/p>\n<p><strong>CONGRESO SOBRE REHABILITACI\u00d3N \/\/\u00a0<\/strong>Entres los eventos complementarios a la feria cer\u00e1mica del pr\u00f3ximo mes destacar\u00e1 el primer Congreso de Rehabilitaci\u00f3n de edificios: conservaci\u00f3n, eficiencia energ\u00e9tica y accesibilidad. El encuentro se desarrollar\u00e1 los d\u00edas 3 y 4 de febrero en el sal\u00f3n de actos de Feria Valencia y fijar\u00e1 su mirada en los \u00faltimos avances en el campo de las reformas. Desde un enfoque t\u00e9cnico, se abordar\u00e1n aspectos como las normativas vigentes o las diferentes ayudas p\u00fablicas que se han activado en los \u00faltimos meses en esta materia.<\/p>\n<p>Adem\u00e1s, se abordar\u00e1n ejemplos pr\u00e1cticos de rehabilitaciones recientes y proyectos singulares que muestren c\u00f3mo el sector est\u00e1 apostando por esta v\u00eda de negocio tras el par\u00f3n en los proyectos de obra nueva. Por \u00faltimo, tambi\u00e9n servir\u00e1 para que se vuelva a reclamar un plan de renovaci\u00f3n de viviendas, una demanda ya cl\u00e1sica del azulejo (y de las restantes industrias del h\u00e1bitat), que no cristaliza en una l\u00ednea de subvenciones clara y efectiva.<\/p>\n<p><strong>ESPACIO COCINA, NUEVA \u00c1REA DE EXPOSICI\u00d3N CON M\u00c1RCAS L\u00cdDERES \/\/\u00a0<\/strong>Cevisama se complementa este a\u00f1o con la puesta en marcha de una zona expositiva adicional: Espacio Cocina, que estar\u00e1 ubicada en el\u00a0<strong>Pabell\u00f3n 6 Alto<\/strong>\u00a0de Feria Valencia. El escaparate ser\u00e1 un punto de encuentro para arquitectos, decoradores, interioristas, puntos de venta e instaladores. Entre las firmas que participar\u00e1n en este certamen de nuevo cu\u00f1o, cabe resaltar a empresas italianas l\u00edderes como Boffi, Schiffini, Zampieri, Record Cuccine, Rastelli, Binova o Bugatti.<\/p>\n<p><strong>POTENCIAR EL CANAL CONTRACT \/\/<\/strong>\u00a0El Foro Internacional de Contract alcanza su cuarta edici\u00f3n y promover\u00e1 m\u00e1s de 350 reuniones de trabajo entre los expositores y representantes de cadenas hoteleras internacionales, y de prescriptores de pa\u00edses como Rusia, Arabia Saud\u00ed, Qatar, India, Suecia, Emiratos \u00c1rabes, Corea del Sur o Colombia.<\/p>\n<p><strong>ASESORAMIENTO DEL ICEX SOBRE MERCADOS CLAVE \/\/\u00a0<\/strong>El ICEX ha programado tres sesiones de los \u2018Caf\u00e9s con expertos\u2019 en el campo de la exportaci\u00f3n. El azulejo en Rusia y sus pa\u00edses de influencia, los CPD\u2019s como oportunidad para acceder a los arquitectos brit\u00e1nicos y el comercio electr\u00f3nico en el mercado alem\u00e1n centrar\u00e1n los encuentros, abiertos a los expositores y que se desarrollar\u00e1n desde el 2 de febrero en la Sala Joaqu\u00edn Rodrigo.<\/p>\n<p><strong>\u00daLTIMOS D\u00cdAS PARA LAS CANDIDATURAS A LOS ALFA \/\/\u00a0<\/strong>El mi\u00e9rcoles finaliza el plazo de presentaci\u00f3n de candidaturas para optar a los Premios Alfa, los galardones que reconocen los mejores avances tecnol\u00f3gicos en la industria y que en febrero cumplir\u00e1n su edici\u00f3n n\u00famero 40. La entrega de las distinciones, a partir de las 17.30 horas en la sala Joaqu\u00edn Rodrigo, ser\u00e1 uno de los puntos \u00e1lgidos de la primera jornada de la feria (1 de febrero).<\/p>\n<p><strong>CICLO DE CONFERENCIAS \/\/<\/strong>\u00a0El Foro de Arquitectura y Dise\u00f1o, constar\u00e1 de las ponencias de Joan Rojeski Studio, del interiorista Francesc Rif\u00e9 y de los arquitectos Sheila O\u00b4Donnell y John Toumey. El ciclo de ponencias congregar\u00e1 a los prescriptores los d\u00edas 3, 4 y 5 de febrero en el llamado \u00c1gora nude.<\/p>\n<p><strong>PROTOTIPOS FUTURISTAS EN TRANS\/HITOS \/\/<\/strong>\u00a0La muestra de arquitectura y dise\u00f1o Trans\/hitos ser\u00e1 uno de los puntos neur\u00e1lgicos de Cevisama. Bajo el lema \u2018Armon\u00edas\u2019, exhibir\u00e1 en sus 600 m2 las virtudes \u2018camale\u00f3nicas\u2019 de la cer\u00e1mica a trav\u00e9s de diferentes proyectos avanzados, entre los que llamar\u00e1 la atenci\u00f3n una c\u00fapula geod\u00e9sica de 7 metros de di\u00e1metro, la \u2018Casita de papel\u2019, creada por el estudio Mixuro, y un trabajo con el sello de la Escuela de Dise\u00f1o de la Universidad de Harvard, entre otros prototipos futuristas.<\/p>\n<p><strong>CONCURSOS \/\/<\/strong>\u00a0Durante Cevisama 2016 estar\u00e1n expuestos en el Foro Centro los mejores trabajos presentados por estudiantes de bellas artes, arquitectura e ingenier\u00edas a los concursos de dise\u00f1o cer\u00e1mico y de ba\u00f1o dentro del ciclo Cevisama Lab. Cada uno de los cert\u00e1menes, que cuenta con dos categor\u00edas diferencias, contar\u00e1 con dos premios, dotados con 2.000 y 1.000 euros. Los galardones se otorgar\u00e1n el \u00faltimo d\u00eda de la feria.<\/p>\n<p><strong>DIVULGACI\u00d3N DE LAS BUENAS PR\u00c1CTICAS DE COLOCACI\u00d3N \/\/<\/strong>\u00a0El Encuentro de Colocadores de Proalso, la asociaci\u00f3n espa\u00f1ola de alicatadores\/soladores, alcanzar\u00e1 su 17\u00aa edici\u00f3n. Las demostraciones en vivo de la cita servir\u00e1n para divulgar las buenas pr\u00e1cticas en la instalaci\u00f3n de cer\u00e1mica. Tambi\u00e9n mostrar\u00e1n en su ubicaci\u00f3n del Nivel 2 Pabell\u00f3n 3 las novedades en adhesivos, perfiler\u00eda y herramientas.<\/p>\n<\/div>","protected":false},"featured_media":14386,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14385","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cevisama 2016, mucho m\u00e1s que una feria comercial - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cevisama 2016, mucho m\u00e1s que una feria comercial - Bathco\" \/>\n<meta property=\"og:description\" content=\"J. CABRERIZO\u00a0\/\u00a0El Peri\u00f3dico del Azulejo Cevisama es, ante todo, una feria comercial al uso, pero en los \u00faltimos a\u00f1os el certamen est\u00e1 incorporando a su oferta numerosos eventos complementarios, algo que se va a potenciar todav\u00eda m\u00e1s en su edici\u00f3n 2016, que se celebrar\u00e1\u00a0del 1 al 5 de febrero en Valencia. El certamen aglutinar\u00e1 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"959\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/\",\"name\":\"Cevisama 2016, mucho m\u00e1s que una feria comercial - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg\",\"datePublished\":\"2016-01-18T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg\",\"width\":959,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cevisama-2016-mucho-mas-que-una-feria-comercial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cevisama 2016, mucho m\u00e1s que una feria comercial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cevisama 2016, mucho m\u00e1s que una feria comercial - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/","og_locale":"en_US","og_type":"article","og_title":"Cevisama 2016, mucho m\u00e1s que una feria comercial - Bathco","og_description":"J. CABRERIZO\u00a0\/\u00a0El Peri\u00f3dico del Azulejo Cevisama es, ante todo, una feria comercial al uso, pero en los \u00faltimos a\u00f1os el certamen est\u00e1 incorporando a su oferta numerosos eventos complementarios, algo que se va a potenciar todav\u00eda m\u00e1s en su edici\u00f3n 2016, que se celebrar\u00e1\u00a0del 1 al 5 de febrero en Valencia. El certamen aglutinar\u00e1 a [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:25+00:00","og_image":[{"width":959,"height":400,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/","url":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/","name":"Cevisama 2016, mucho m\u00e1s que una feria comercial - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg","datePublished":"2016-01-18T00:00:00+00:00","dateModified":"2025-10-30T12:39:25+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/12989_es-cevisama-2016-mucho-mas-que-una-feria-comercial-l-foto-cevisama-Real.jpg","width":959,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/cevisama-2016-mucho-mas-que-una-feria-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Cevisama 2016, mucho m\u00e1s que una feria comercial"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14386"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14385"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}