{"id":14437,"date":"2016-04-07T00:00:00","date_gmt":"2016-04-07T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/"},"modified":"2025-10-30T12:39:25","modified_gmt":"2025-10-30T12:39:25","slug":"bathco-presente-en-la-exposicion-adesign-santander","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/","title":{"rendered":"Bathco presente en la exposici\u00f3n A\u00b4Design Santander"},"content":{"rendered":"<p>A punto de cumplir un a\u00f1o de la creaci\u00f3n del Bathco Atelier, la empresa c\u00e1ntabra continua su apuesta por el arte y el dise\u00f1o patrocinando la exposici\u00f3n y el ciclo de conferencias \u201cLos mejores dise\u00f1os del mundo 2015\u2033 que se celebrar\u00e1 del 7 de abril al 12 de mayo en el Colegio de Arquitectos de Cantabria.<\/p>\n<p>A\u2019 Design Santander albergar\u00e1 algunos proyectos de arquitectura, interiorismo y dise\u00f1o galardonados en la pasada edici\u00f3n de los A\u2019 Design Award en Italia. Bathco ha querido implicarse en esta iniciativa y, adem\u00e1s de patrocinar la exposici\u00f3n,\u00a0 estar\u00e1 presente con la colecci\u00f3n Bathco Atelier.<\/p>\n<p>Los visitantes que acudan a la exposici\u00f3n A\u00b4Design Santander podr\u00e1n apreciar una serie de lavabos que han sido intervenidos por los artistas que forman parte del atelier de Bathco. Se trata de piezas \u00fanicas, obras de arte en s\u00ed mismas que han sido expuestas por Bathco en ferias internacionales como Art Bassel (Miami), Big 5 (Dubai) y Cersaie (Italia) y que, por primera vez, se traen a Santander.<\/p>\n<p><strong>Exposici\u00f3n A\u00b4Design Santander<\/strong><\/p>\n<p>Por primera vez en Espa\u00f1a y despu\u00e9s de pasar por ciudades como, Shenzhen (China), Sao Paulo y\u00a0 Dubl\u00edn, la exposici\u00f3n de los prestigiosos premios de dise\u00f1o A\u00b4Design Award &amp; Competition, recala en Santander, donde contempor\u00e1neamente se celebrar\u00e1 un ciclo de conferencias en torno al dise\u00f1o y la arquitectura.<\/p>\n<p>Una oportunidad exclusiva para conocer los trabajos de dise\u00f1adores, artistas y profesionales de la arquitectura, interiorismo y otras categor\u00edas, reconocidos en el panorama internacional, adem\u00e1s de participar en unos encuentros divulgativos y de networking \u00fanicos en Espa\u00f1a.<\/p>\n<p>Jose Angel Cicero, arquitecto y promotor cultural, ganador de un Platinum A\u00b4Design Award con su proyecto SantanderWorld que estuvo presente durante la celebraci\u00f3n del mundial de vela 2014, organiza y comisaria esta exposici\u00f3n junto con el Colegio de Arquitectos de Cantabria y\u00a0 10Deco, con la colaboraci\u00f3n del Gobierno de Cantabria y Acav (Asociaci\u00f3n C\u00e1ntabra de Artistas Visuales).<\/p>\n<p>La exposici\u00f3n de los paneles de los ganadores de las diferentes categor\u00edas se podr\u00e1 ver \u00a0del 7 de abril al 12 de mayo en el Colegio de Arquitectos en la calle de Aguayos 5 de Santander en horario de lunes a viernes de 17:30 a 21:00 hrs. y de s\u00e1bado a domingo de 11:00 a 14:00 hrs. Con entrada libre.<\/p>\n<p>En paralelo a la exposici\u00f3n, cada jueves del 14 de abril al 5 de mayo, se celebrar\u00e1n conferencias referentes al dise\u00f1o, la arquitectura, la moda y el arte.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre la exposici\u00f3n y conferencias:<\/p>\n<p><a href=\"http:\/\/www.10decoracion.com\/exposicion-diseno-en-santander-adesign\/\">http:\/\/www.10decoracion.com\/exposicion-diseno-en-santander-adesign\/<\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"featured_media":14438,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14437","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bathco presente en la exposici\u00f3n A\u00b4Design Santander - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bathco presente en la exposici\u00f3n A\u00b4Design Santander - Bathco\" \/>\n<meta property=\"og:description\" content=\"A punto de cumplir un a\u00f1o de la creaci\u00f3n del Bathco Atelier, la empresa c\u00e1ntabra continua su apuesta por el arte y el dise\u00f1o patrocinando la exposici\u00f3n y el ciclo de conferencias \u201cLos mejores dise\u00f1os del mundo 2015\u2033 que se celebrar\u00e1 del 7 de abril al 12 de mayo en el Colegio de Arquitectos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15129_es-cartel-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/\",\"name\":\"Bathco presente en la exposici\u00f3n A\u00b4Design Santander - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/15129_es-cartel-Real.jpg\",\"datePublished\":\"2016-04-07T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/15129_es-cartel-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/15129_es-cartel-Real.jpg\",\"width\":586,\"height\":896},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-presente-en-la-exposicion-adesign-santander\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bathco presente en la exposici\u00f3n A\u00b4Design Santander\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bathco presente en la exposici\u00f3n A\u00b4Design Santander - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/","og_locale":"en_US","og_type":"article","og_title":"Bathco presente en la exposici\u00f3n A\u00b4Design Santander - Bathco","og_description":"A punto de cumplir un a\u00f1o de la creaci\u00f3n del Bathco Atelier, la empresa c\u00e1ntabra continua su apuesta por el arte y el dise\u00f1o patrocinando la exposici\u00f3n y el ciclo de conferencias \u201cLos mejores dise\u00f1os del mundo 2015\u2033 que se celebrar\u00e1 del 7 de abril al 12 de mayo en el Colegio de Arquitectos de [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:25+00:00","og_image":[{"width":586,"height":896,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15129_es-cartel-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/","url":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/","name":"Bathco presente en la exposici\u00f3n A\u00b4Design Santander - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15129_es-cartel-Real.jpg","datePublished":"2016-04-07T00:00:00+00:00","dateModified":"2025-10-30T12:39:25+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15129_es-cartel-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15129_es-cartel-Real.jpg","width":586,"height":896},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-presente-en-la-exposicion-adesign-santander\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Bathco presente en la exposici\u00f3n A\u00b4Design Santander"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14438"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14437"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}