{"id":14479,"date":"2016-06-06T00:00:00","date_gmt":"2016-06-06T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/"},"modified":"2025-10-30T12:39:26","modified_gmt":"2025-10-30T12:39:26","slug":"cantabria-mas-global","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/cantabria-mas-global\/","title":{"rendered":"Cantabria m\u00e1s global"},"content":{"rendered":"<p>Isabel Arozamena.- \u00abLas peque\u00f1as y medianas empresas (pymes) que exportan son m\u00e1s competitivas y crean m\u00e1s empleo\u00bb. Diego L\u00f3pez Garrido, exsecretario de Estado para la Uni\u00f3n Europea entre los a\u00f1os 2008 y 2011, ha protagonizado la primera de las tres conferencias programadas por El Diario Monta\u00f1\u00e9s, con la colaboraci\u00f3n del gobierno de Cantabria y Soderc\u00e1n, sobre el futuro estrat\u00e9gico de la industria de Cantabria.<\/p>\n<p>En esta ocasi\u00f3n el tema a tratar ha sido la importancia de la internacionalizaci\u00f3n, mientras que los dos siguientes foros ser\u00e1n los d\u00edas 14 y 23 de junio, en el hotel Sardinero, y corresponder\u00e1n a la presidenta de la Fundaci\u00f3n Cotec, Cristina Garmendia, y al directivo de Vodafone, Miguel \u00c1ngel Cervera, que hablar\u00e1n de la transferencia de la investigaci\u00f3n y las necesidades de las nuevas empresas.<\/p>\n<p>L\u00f3pez Garrido se ha mostrado firme defensor de la salida al exterior de las empresas, las grandes y las peque\u00f1as, y para reafirmar su tesis ha expuesto varios informes elaborados por la Comisi\u00f3n Europea que reflejan que la internacionalizaci\u00f3n es clave para el desarrollo de las compa\u00f1\u00edas. \u00abLas empresas que no exportan crean la mitad del empleo que las que exportan\u00bb, ya que el empleo en las primeras crece al 2% mientras que en el caso de que las que s\u00ed salen al exterior llega al 7%.<\/p>\n<p>Una vez sentada la premisa de que las empresas que salen al exterior son m\u00e1s competitivas, L\u00f3pez Garrido apuesta por fomentar las ventas a pa\u00edses de fuera de la Uni\u00f3n Europea y los llamados emergentes. El 80% de las exportaciones de las empresas espa\u00f1olas tienen como destino Europa, principalmente a pa\u00edses de la Uni\u00f3n Europea.<\/p>\n<p>Para impulsar este comercio m\u00e1s all\u00e1 de las fronteras europeas, L\u00f3pez Garrido ha mencionado \u00abla importancia\u00bb que en este escenario tendr\u00e1 el tratado de libre comercio con Estados Unidos, el denominado TTIP, y tambi\u00e9n el que se proyecta con Canad\u00e1. En ambos casos, ha recalcado que el G-7 tiene la intenci\u00f3n de aprobar este a\u00f1o.<\/p>\n<p>L\u00f3pez Garrido es director del estudio que se acaba de presentar &#8216;El estado de la Uni\u00f3n Europea. La encrucijada pol\u00edtica de Europa&#8217;, un documento de 149 p\u00e1ginas en el que se analiza la cr\u00edtica situaci\u00f3n del bloque comunitario. Adem\u00e1s es autor del libro &#8216;La edad de hierro&#8217; referido a la gran crisis \u00abde la que todav\u00eda no hemos salido\u00bb, ha asegurado.<\/p>\n<p>Ana Cobo, directora de Exportaci\u00f3n de Bathco, empresa c\u00e1ntabra especializada en el sector de los sanitarios, y Carlos Raba, director de Santander Teleport, explicaron su experiencia al tratarse de dos empresas de la comunidad aut\u00f3noma que apuestan decididamente por salir al exterior.<\/p>\n<p>Bathco tiene relaciones comerciales con un total de 70 pa\u00edses gracias \u00aba la firme voluntad del fundador de la compa\u00f1\u00eda hace 40 a\u00f1os\u00bb. Cobo ha explicado que la vinculaci\u00f3n de la empresa con el sector de la construcci\u00f3n, en crisis en el mercado nacional, ha obligado a la internacionalizaci\u00f3n.<\/p>\n<p>En el caso del Teleport, las caracter\u00edsticas de esta empresa tecnol\u00f3gica e innovadora, junto a Erzia, han hecho de la internacionalizaci\u00f3n una pr\u00e1ctica habitual. Bathco exporta cerca de un 60% de sus productos.<\/p>\n<p>\u00a0<\/p>\n<p>Fuente: <a title=\"El Diario Monta\u00f1\u00e9s\" href=\"http:\/\/www.eldiariomontanes.es\/cantabria\/201606\/06\/empresas-exportan-competitivas-crean-20160606132815.html\">El Diario Monta\u00f1\u00e9s<\/a><\/p>","protected":false},"featured_media":14480,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14479","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cantabria m\u00e1s global - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/cantabria-mas-global\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cantabria m\u00e1s global - Bathco\" \/>\n<meta property=\"og:description\" content=\"Isabel Arozamena.- \u00abLas peque\u00f1as y medianas empresas (pymes) que exportan son m\u00e1s competitivas y crean m\u00e1s empleo\u00bb. Diego L\u00f3pez Garrido, exsecretario de Estado para la Uni\u00f3n Europea entre los a\u00f1os 2008 y 2011, ha protagonizado la primera de las tres conferencias programadas por El Diario Monta\u00f1\u00e9s, con la colaboraci\u00f3n del gobierno de Cantabria y Soderc\u00e1n, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/cantabria-mas-global\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1289\" \/>\n\t<meta property=\"og:image:height\" content=\"902\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/\",\"name\":\"Cantabria m\u00e1s global - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg\",\"datePublished\":\"2016-06-06T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg\",\"width\":1289,\"height\":902},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/cantabria-mas-global\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cantabria m\u00e1s global\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cantabria m\u00e1s global - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/cantabria-mas-global\/","og_locale":"en_US","og_type":"article","og_title":"Cantabria m\u00e1s global - Bathco","og_description":"Isabel Arozamena.- \u00abLas peque\u00f1as y medianas empresas (pymes) que exportan son m\u00e1s competitivas y crean m\u00e1s empleo\u00bb. Diego L\u00f3pez Garrido, exsecretario de Estado para la Uni\u00f3n Europea entre los a\u00f1os 2008 y 2011, ha protagonizado la primera de las tres conferencias programadas por El Diario Monta\u00f1\u00e9s, con la colaboraci\u00f3n del gobierno de Cantabria y Soderc\u00e1n, [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/cantabria-mas-global\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:26+00:00","og_image":[{"width":1289,"height":902,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/","url":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/","name":"Cantabria m\u00e1s global - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg","datePublished":"2016-06-06T00:00:00+00:00","dateModified":"2025-10-30T12:39:26+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/15909_es-cantabria-mas-global-el-diario-montanes-Real.jpg","width":1289,"height":902},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/cantabria-mas-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Cantabria m\u00e1s global"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14480"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14479"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}