{"id":14697,"date":"2017-04-10T00:00:00","date_gmt":"2017-04-10T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/"},"modified":"2025-10-30T12:39:29","modified_gmt":"2025-10-30T12:39:29","slug":"nuevas-curvas-en-el-bano","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/nuevas-curvas-en-el-bano\/","title":{"rendered":"Nuevas curvas en el ba\u00f1o"},"content":{"rendered":"<p>Tres modelos del cat\u00e1logo de la compa\u00f1\u00eda se renuevan reduciendo el grosor de sus paredes lo que aporta un plus de elegancia al espacio del tocador. El dise\u00f1o de las piezas se ha desarrollado pensando en la curva como un factor de una sutileza \u00fanica y con el objetivo de crear ambientes con un aire renovado.<\/p>\n<p>El lavabo New Magdalena con referencia 0092BN llega en formato rectangular con la opci\u00f3n de colocarlo sobre encimera, sin rebosadero y con la siguiente medida 575x325x160 mm.<\/p>\n<p>En cuanto a lavabos ovales, se pueden encontrar dos modelos sin rebosadero y para colocar sobre encimera. New Toulouse tiene una medida de 588 x 422 x 138 mm. Y se puede encontrar con la referencia 4037N, mientras que New M\u00e1laga con referencia 0034N mide 598 x 408 x 139 mm. y llega con peana para grifo incorporada.<\/p>\n<p>Estos tres lavabos se pueden encontrar tanto en porcelana blanca como en porcelana natural para adaptarse a la est\u00e9tica de cualquier espacio.<\/p>\n<p>Para conocer m\u00e1s caracter\u00edsticas de cada uno de los modelos se puede visitar la p\u00e1gina web de la compa\u00f1\u00eda. A continuaci\u00f3n se encuentran los enlaces a cada uno de ellos:<\/p>\n<p><a title=\"New Toulouse en porcelana blanca\" href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/oval\/new-toulouse.html\/\"><strong>NEW TOULOUSE<\/strong> en porcelana blanca<\/a> and <a title=\"Natural porcelain\" href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/oval\/new-toulouse-cru.html\/\">natural porcelain<\/a><\/p>\n<p><a title=\"Porcelana blanca\" href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/oval\/new-malaga.html\/\"><strong>NEW M\u00c1LAGA<\/strong> en porcelana blanca<\/a> and <a title=\"New M\u00e1laga en porcelana natural\" href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/oval\/new-malaga-cru.html\/\">natural porcelain<\/a><\/p>\n<p><a title=\"New Magdalena en porcelana blanca\" href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/rectangular\/new-magdalena.html\/\"><strong>NEW MAGDALENA<\/strong> en porcelana blanca<\/a> and\u00a0<a title=\"New Magdalena en porcelana natural\" href=\"https:\/\/www.thebathcollection.com\/en\/producto\/washbasins\/porcelana\/rectangular\/new-magdalena-cru.html\/\">natural porcelain<\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"featured_media":14698,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14697","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevas curvas en el ba\u00f1o - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/nuevas-curvas-en-el-bano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevas curvas en el ba\u00f1o - Bathco\" \/>\n<meta property=\"og:description\" content=\"Tres modelos del cat\u00e1logo de la compa\u00f1\u00eda se renuevan reduciendo el grosor de sus paredes lo que aporta un plus de elegancia al espacio del tocador. El dise\u00f1o de las piezas se ha desarrollado pensando en la curva como un factor de una sutileza \u00fanica y con el objetivo de crear ambientes con un aire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/nuevas-curvas-en-el-bano\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/19961_es-0092bn-magdalena-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1934\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/\",\"name\":\"Nuevas curvas en el ba\u00f1o - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/19961_es-0092bn-magdalena-Real.jpg\",\"datePublished\":\"2017-04-10T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/19961_es-0092bn-magdalena-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/19961_es-0092bn-magdalena-Real.jpg\",\"width\":1934,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/nuevas-curvas-en-el-bano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuevas curvas en el ba\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevas curvas en el ba\u00f1o - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/nuevas-curvas-en-el-bano\/","og_locale":"en_US","og_type":"article","og_title":"Nuevas curvas en el ba\u00f1o - Bathco","og_description":"Tres modelos del cat\u00e1logo de la compa\u00f1\u00eda se renuevan reduciendo el grosor de sus paredes lo que aporta un plus de elegancia al espacio del tocador. El dise\u00f1o de las piezas se ha desarrollado pensando en la curva como un factor de una sutileza \u00fanica y con el objetivo de crear ambientes con un aire [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/nuevas-curvas-en-el-bano\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:29+00:00","og_image":[{"width":1934,"height":1200,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/19961_es-0092bn-magdalena-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/","url":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/","name":"Nuevas curvas en el ba\u00f1o - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/19961_es-0092bn-magdalena-Real.jpg","datePublished":"2017-04-10T00:00:00+00:00","dateModified":"2025-10-30T12:39:29+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/19961_es-0092bn-magdalena-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/19961_es-0092bn-magdalena-Real.jpg","width":1934,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/nuevas-curvas-en-el-bano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Nuevas curvas en el ba\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14698"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14697"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}