{"id":14738,"date":"2017-07-31T00:00:00","date_gmt":"2017-07-31T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/"},"modified":"2025-10-30T12:39:29","modified_gmt":"2025-10-30T12:39:29","slug":"lanzamos-el-nuevo-catalogo-general-2017","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/","title":{"rendered":"Lanzamos el nuevo cat\u00e1logo general 2017"},"content":{"rendered":"<p>El nuevo cat\u00e1logo general 2017 de Bathco mantiene los productos de continuidad y a\u00f1ade una amplia serie novedades. La apuesta de Bathco se centra en los nuevos materiales para el ba\u00f1o y la diversidad de colecciones para seguir sorprendiendo a clientes y distribuidores.<\/p>\n<p>El esp\u00edritu innovador de la compa\u00f1\u00eda hace que se trabaje de forma constante en el dise\u00f1o de nuevos productos y en la investigaci\u00f3n de nuevos materiales, as\u00ed cada colecci\u00f3n se convierte en algo vivo y en constante renovaci\u00f3n.<\/p>\n<p>En las primeras p\u00e1ginas del cat\u00e1logo se presenta la empresa, su forma de trabajar, su proyecci\u00f3n internacional y toda una serie de proyectos en los que est\u00e1n presentes productos de Bathco alrededor del mundo; ya son m\u00e1s de 90 clientes de los cinco continentes que conf\u00edan en sus productos.<\/p>\n<p><strong>NOVEDADES 2017<\/strong><\/p>\n<p>En el apartado de sanitarios destacan nuevas familias como New Ronda, New Toledo o Lagos tanto en su l\u00ednea suspendida como a suelo. En cuanto a los lavabos de porcelana se ha querido evolucionar a l\u00edneas m\u00e1s sencillas y delicadas, surgen as\u00ed nuevos modelos como New Toulouse, New Magdalena y New M\u00e1laga que conviven con sus versiones m\u00e1s cl\u00e1sicas. La l\u00ednea Contract se refuerza con los lavabos Riga, Bucarest, Helsinki, Copenhague, Oslo y Praga.<\/p>\n<p>Lo m\u00e1s novedoso este a\u00f1o es la introducci\u00f3n de un nuevo material, el acero y el aluminio. Este tipo de materiales permiten diferentes acabados, lo que aporta gran versatilidad. As\u00ed los lavabos Begur, Altea y Denia se presentan en aluminio esmaltado y r\u00fastico. Mientras el modelo Noja aparece en diferentes combinaciones de colores metalizados. El acero m\u00e1s puro se puede ver en los modelos As\u00f3n, Oru\u00f1a y Gama.<\/p>\n<p>En el apartado de complementos adquieren gran protagonismo los pedestales y las encimeras. Cabe destacar el pedestal c\u00f3nico de acacia y aluminio que recientemente ha sido galardonado con un Silver A\u2019Design Award en la categor\u00eda Bathroom Furniture and Sanitary Ware.<\/p>\n<p><strong>EL CAT\u00c1LOGO<\/strong><\/p>\n<p>El nuevo cat\u00e1logo 2017 ya est\u00e1 disponible en formato papel. En cuanto a la versi\u00f3n digital <strong><a title=\"Cat\u00e1logo general 2017\" href=\"https:\/\/www.thebathcollection.com\/en\/default\/documentos\/155_es-catalogo_general_2017.pdf\/\">se puede descargar en la web de la compa\u00f1\u00eda.<\/a><\/strong><\/p>","protected":false},"featured_media":14739,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14738","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lanzamos el nuevo cat\u00e1logo general 2017 - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lanzamos el nuevo cat\u00e1logo general 2017 - Bathco\" \/>\n<meta property=\"og:description\" content=\"El nuevo cat\u00e1logo general 2017 de Bathco mantiene los productos de continuidad y a\u00f1ade una amplia serie novedades. La apuesta de Bathco se centra en los nuevos materiales para el ba\u00f1o y la diversidad de colecciones para seguir sorprendiendo a clientes y distribuidores. El esp\u00edritu innovador de la compa\u00f1\u00eda hace que se trabaje de forma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/21254_es-catalogo-general-2017-bathco-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1934\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/\",\"name\":\"Lanzamos el nuevo cat\u00e1logo general 2017 - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/21254_es-catalogo-general-2017-bathco-Real.jpg\",\"datePublished\":\"2017-07-31T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/21254_es-catalogo-general-2017-bathco-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/21254_es-catalogo-general-2017-bathco-Real.jpg\",\"width\":1934,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lanzamos-el-nuevo-catalogo-general-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lanzamos el nuevo cat\u00e1logo general 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lanzamos el nuevo cat\u00e1logo general 2017 - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/","og_locale":"en_US","og_type":"article","og_title":"Lanzamos el nuevo cat\u00e1logo general 2017 - Bathco","og_description":"El nuevo cat\u00e1logo general 2017 de Bathco mantiene los productos de continuidad y a\u00f1ade una amplia serie novedades. La apuesta de Bathco se centra en los nuevos materiales para el ba\u00f1o y la diversidad de colecciones para seguir sorprendiendo a clientes y distribuidores. El esp\u00edritu innovador de la compa\u00f1\u00eda hace que se trabaje de forma [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:29+00:00","og_image":[{"width":1934,"height":1200,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/21254_es-catalogo-general-2017-bathco-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/","url":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/","name":"Lanzamos el nuevo cat\u00e1logo general 2017 - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/21254_es-catalogo-general-2017-bathco-Real.jpg","datePublished":"2017-07-31T00:00:00+00:00","dateModified":"2025-10-30T12:39:29+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/21254_es-catalogo-general-2017-bathco-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/21254_es-catalogo-general-2017-bathco-Real.jpg","width":1934,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/lanzamos-el-nuevo-catalogo-general-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Lanzamos el nuevo cat\u00e1logo general 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14739"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14738"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}