{"id":14790,"date":"2018-04-12T00:00:00","date_gmt":"2018-04-12T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/"},"modified":"2025-10-30T12:39:30","modified_gmt":"2025-10-30T12:39:30","slug":"griferia-athenas-e-iconos","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/griferia-athenas-e-iconos\/","title":{"rendered":"Grifer\u00eda Athenas e Iconos"},"content":{"rendered":"<p>Monomandos cil\u00edndricos, robustos y firmes que se pueden encontrar en acero cepillado y negro mate. Las nuevas referencias se convierten en foco de todas las miradas gracias a un dise\u00f1o muy cuidado y dirigido a lavabos, ba\u00f1eras y duchas bajo el nombre de dos familias ATHENAS e ICONOS.<\/p>\n<p>En Athenas encontramos piezas monomando con una peque\u00f1a manecilla sencilla que ayuda a la apertura y el ca\u00f1o termina en curva haciendo que el agua caiga directamente sobre la superficie del lavabo desde diferentes alturas ya que se pueden encontrar grifos para lavabo bajos, medios y altos. Por su parte, se presenta el modelo empotrado a pared que aporta m\u00e1s espacio \u00fatil en la zona del lavabo. Por primera vez, Bathco presenta grifer\u00eda a suelo perfecta para lavabo o para ba\u00f1eras exentas, present\u00e1ndose como una propuesta que estiliza el ambiente.<\/p>\n<p>La grifer\u00eda de ducha de la serie Athenas se compone de tres piezas. El grifo monomando empotrado mantiene el cuerpo oculto para facilitar la limpieza y crear un espacio de ducha m\u00e1s est\u00e9tico. Lo mismo ocurre con el mango con codo de pared integrado y con el cabezal que, gracias a su di\u00e1metro permite un efecto lluvia para esos espacios que buscan un ba\u00f1o-spa.<\/p>\n<p>Iconos simplifica las l\u00edneas eliminando la manecilla ya que el mando surge como una extensi\u00f3n del pie del grifo. El ca\u00f1o se alza en \u00e1ngulo recto perpendicular al cuerpo de la pieza con un dise\u00f1o sutil y cil\u00edndrico. En la serie Iconos se encuentran grifos para lavabo bajos y altos, as\u00ed como a suelo para lavabo y ba\u00f1era.<\/p>\n<p>Todos los modelos se pueden encontrar en acero inoxidable cepillado y en negro mate para adaptarlo a diferentes ambientes.<\/p>","protected":false},"featured_media":14791,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14790","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grifer\u00eda Athenas e Iconos - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/griferia-athenas-e-iconos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grifer\u00eda Athenas e Iconos - Bathco\" \/>\n<meta property=\"og:description\" content=\"Monomandos cil\u00edndricos, robustos y firmes que se pueden encontrar en acero cepillado y negro mate. Las nuevas referencias se convierten en foco de todas las miradas gracias a un dise\u00f1o muy cuidado y dirigido a lavabos, ba\u00f1eras y duchas bajo el nombre de dos familias ATHENAS e ICONOS. En Athenas encontramos piezas monomando con una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/griferia-athenas-e-iconos\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1934\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/\",\"name\":\"Grifer\u00eda Athenas e Iconos - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg\",\"datePublished\":\"2018-04-12T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg\",\"width\":1934,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/griferia-athenas-e-iconos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grifer\u00eda Athenas e Iconos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grifer\u00eda Athenas e Iconos - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/griferia-athenas-e-iconos\/","og_locale":"en_US","og_type":"article","og_title":"Grifer\u00eda Athenas e Iconos - Bathco","og_description":"Monomandos cil\u00edndricos, robustos y firmes que se pueden encontrar en acero cepillado y negro mate. Las nuevas referencias se convierten en foco de todas las miradas gracias a un dise\u00f1o muy cuidado y dirigido a lavabos, ba\u00f1eras y duchas bajo el nombre de dos familias ATHENAS e ICONOS. En Athenas encontramos piezas monomando con una [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/griferia-athenas-e-iconos\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:30+00:00","og_image":[{"width":1934,"height":1200,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/","url":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/","name":"Grifer\u00eda Athenas e Iconos - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg","datePublished":"2018-04-12T00:00:00+00:00","dateModified":"2025-10-30T12:39:30+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/23285_es-nuevas-colecciones-de-grifos-para-el-bano-de-bathco-Real.jpg","width":1934,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/griferia-athenas-e-iconos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Grifer\u00eda Athenas e Iconos"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14791"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14790"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}