{"id":14809,"date":"2018-10-08T00:00:00","date_gmt":"2018-10-08T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/"},"modified":"2025-10-30T12:39:30","modified_gmt":"2025-10-30T12:39:30","slug":"las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/","title":{"rendered":"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018"},"content":{"rendered":"<p>Bathco ha tenido una calurosa acogida en la feria de referencia de equipamiento de ba\u00f1o celebrada del 24 al 28 de septiembre en Bolonia. Parte de este \u00e9xito se debe al dise\u00f1o de un stand que ha sabido resaltar cada una de las piezas presentadas.<\/p>\n<p>Este \u00e9xito se refleja tambi\u00e9n en los visitantes que han pasado por su stand para conocer de primera mano las novedades presentadas por la compa\u00f1\u00eda. La presencia m\u00e1s relevante ha sido la del<strong> continente europeo<\/strong> que ha supuesto el 74 % de las visitas, seguido de Francia o Espa\u00f1a. Tambi\u00e9n tuvieron su peso los visitantes de Alemania, Polonia y Grecia. A su vez, tambi\u00e9n han sido significativos los contactos creados con empresas del continente <strong>asi\u00e1tico<\/strong> \u00a0and <strong>americano.<\/strong><\/p>\n<p>En palabras del director general de la compa\u00f1\u00eda, Jos\u00e9 L\u00f3pez Cort\u00e9s, \u00a0\u201cCersaie se ha convertido en un referente en el dise\u00f1o e interiorismo del ba\u00f1o. De ah\u00ed que nuestra apuesta a la hora de presentar producto sea cada vez m\u00e1s exigente. Este a\u00f1o estamos muy satisfechos con nuestra participaci\u00f3n\u201d.<\/p>\n<p>Con este escenario de fondo, Bathco ha presentado al mundo nuevas piezas y \u00a0colecciones donde el material y el dise\u00f1o han sido los aut\u00e9nticos protagonistas.<\/p>","protected":false},"featured_media":14810,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14809","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018 - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018 - Bathco\" \/>\n<meta property=\"og:description\" content=\"Bathco ha tenido una calurosa acogida en la feria de referencia de equipamiento de ba\u00f1o celebrada del 24 al 28 de septiembre en Bolonia. Parte de este \u00e9xito se debe al dise\u00f1o de un stand que ha sabido resaltar cada una de las piezas presentadas. Este \u00e9xito se refleja tambi\u00e9n en los visitantes que han [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/\",\"name\":\"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018 - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg\",\"datePublished\":\"2018-10-08T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018 - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/","og_locale":"en_US","og_type":"article","og_title":"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018 - Bathco","og_description":"Bathco ha tenido una calurosa acogida en la feria de referencia de equipamiento de ba\u00f1o celebrada del 24 al 28 de septiembre en Bolonia. Parte de este \u00e9xito se debe al dise\u00f1o de un stand que ha sabido resaltar cada una de las piezas presentadas. Este \u00e9xito se refleja tambi\u00e9n en los visitantes que han [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:30+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/","url":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/","name":"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018 - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg","datePublished":"2018-10-08T00:00:00+00:00","dateModified":"2025-10-30T12:39:30+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24294_es-photos-bathco-cersaie-2018-low-res-47-Real-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/las-ultimas-novedades-de-bathco-sorprenden-en-cersaie-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Las \u00faltimas novedades de Bathco sorprenden en Cersaie 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14810"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14809"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}