{"id":14855,"date":"2019-01-02T00:00:00","date_gmt":"2019-01-02T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/"},"modified":"2025-10-30T12:39:31","modified_gmt":"2025-10-30T12:39:31","slug":"bathco-hace-balance-del-2018-para-impulsarse-hacia-2019","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/","title":{"rendered":"Bathco hace balance del 2018 para impulsarse hacia 2019"},"content":{"rendered":"<p>A continuaci\u00f3n se hace un resumen de los hitos de la compa\u00f1\u00eda de estos 12 meses. Comenz\u00f3 lanzando el nuevo cat\u00e1logo <span style=\"text-decoration: underline;\">Natural Series<\/span>, un documento que presenta piezas con un dise\u00f1o muy cuidado y con el material como protagonista. En la feria de <span style=\"text-decoration: underline;\">Cevisama<\/span> que se celebr\u00f3 en febrero se presentaron nuevos productos totalmente novedosos para el ba\u00f1o: lavabos de acero, aluminio y zinc, nueva grifer\u00eda, muebles y encimeras as\u00ed como los nuevos modelos de DadoQuartz. Sin olvidar las nuevas referencias en lavabos de porcelana e inodoros que mejoran su dise\u00f1o y funcionalidades.<\/p>\n<p>Las piezas que surgieron de Bathco Atelier fueron el foco de atenci\u00f3n en septiembre en la feria <span style=\"text-decoration: underline;\">Cersaie<\/span>. La inspiraci\u00f3n se encontr\u00f3 en los materiales constructivos y estampados de otras \u00e9pocas para ofrecer nuevos ambientes en el ba\u00f1o.<\/p>\n<p>Con el cat\u00e1logo de novedades <span style=\"text-decoration: underline;\">Making Experiences<\/span> llegaron piezas que adquieren personalidad propia y son capaces de provocar una amalgama de sensaciones a trav\u00e9s del contacto con diferentes materiales, texturas y acabados.<\/p>\n<p>El a\u00f1o se cerr\u00f3 mirando hacia 2019, un a\u00f1o que promete estar lleno de novedades de principio a fin. A continuaci\u00f3n se detallan las ferias en las que Bathco estar\u00e1 presente.<\/p>\n<p><a title=\"Cas Decor 2019\" href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/ferias-eventos\/casa-decor-2019.html\/\" target=\"_blank\"><strong>Casa Decor<\/strong><\/a><br \/>24 de enero &#8211; 10 de marzo, Madrid (Espa\u00f1a)<\/p>\n<p>Bathco participar\u00e1 por primera vez en Casa Decor, la exclusiva exposici\u00f3n de interiorismo con un formato \u00fanico en Europa. Una selecci\u00f3n de productos de la compa\u00f1\u00eda c\u00e1ntabra se podr\u00e1 ver del 24 de enero al 10 de marzo en la calle N\u00fa\u00f1ez de Balboa n\u00ba 86 gracias al estudio de interiorismo Cynthia Rom\u00e1n. Este equipo de profesionales es el encargado de habilitar los ba\u00f1os p\u00fablicos del edificio que recibe m\u00e1s de 40.000 visitantes por edici\u00f3n, es decir, alrededor de mil personas diarias.<\/p>\n<p><a title=\"Cevisama 2019\" href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/ferias-eventos\/cevisama-2019.html\/\" target=\"_blank\"><strong>Cevisama<\/strong><\/a><br \/>28 de enero &#8211; 1 de febrero, Valencia (Espa\u00f1a)<\/p>\n<p>Bathco no pod\u00eda faltar a una cita m\u00e1s de la feria de Valencia. Muchas son las novedades que presentar\u00e1 en la edici\u00f3n de 2019; nuevos trabajos de Bathco Atelier, nuevas propuestas para murales cer\u00e1micos, muebles modulares y una nueva l\u00ednea de lavabos dise\u00f1ada junto al dise\u00f1ador Lucio Traficante, que responden a las morfolog\u00edas geom\u00e9tricas del \u201chandmade eco net\u201d. Los nuevos modelos est\u00e1n fabricados en madera torneada y Solid Surface. La madera, una material noble y tradicional, en contraposici\u00f3n de un material high tech y moderno como el Solid Surface, genera una contradicci\u00f3n o dicotom\u00eda arm\u00f3nica que da como resultado un objeto equilibrado y bien proporcionado.<\/p>\n<p>El stand de la compa\u00f1\u00eda estar\u00e1 situado en el N3 P2 B41. <a title=\"Cevisama 2019\" href=\"https:\/\/cevisama.feriavalencia.com\/visitantes-5\/informacion-y-registro\/\" target=\"_blank\"><strong>Se puede conseguir la entrada pulsando aqu\u00ed.<\/strong><\/a><\/p>\n<p><a title=\"ISH 2019\" href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/ferias-eventos\/ish-2019.html\/\" target=\"_blank\"><strong>ISH<\/strong><\/a><br \/>11 &#8211; 15 de marzo, Frankfurt (Alemania)<\/p>\n<p>Bathco estar\u00e1 presente en la pr\u00f3xima edici\u00f3n de ISH, el escaparate m\u00e1s grande del mundo del equipamiento para el ba\u00f1o, construcci\u00f3n, energ\u00eda, climatizaci\u00f3n y energ\u00edas renovables. Del 11 al 15 de marzo la empresa c\u00e1ntabra mostrar\u00e1 una gama totalmente novedosa de productos en la feria de Frankfurt.<\/p>\n<p><a title=\"Cersaie 2019\" href=\"https:\/\/www.thebathcollection.com\/en\/actualidad\/ferias-eventos\/cersaie-2019.html\/\" target=\"_blank\"><strong>Cersaie<\/strong><\/a><br \/>23 &#8211; 27 de septiembre, Bologna (Italia)<\/p>\n<p>La cita anual m\u00e1s influyente del mundo de la cer\u00e1mica a nivel mundial volver\u00e1 a desarrollarse entre el 23 y el 27 de septiembre en la feria de Bolonia. Durante 5 d\u00edas las empresas internacionales se re\u00fanen con arquitectos, dise\u00f1adores, contratistas y minoristas y muestran las nuevas tendencias en superficies cer\u00e1micas, papeles pintados, pisos de madera, m\u00e1rmol y muebles y accesorios de ba\u00f1o.<\/p>","protected":false},"featured_media":14856,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14855","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bathco hace balance del 2018 para impulsarse hacia 2019 - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bathco hace balance del 2018 para impulsarse hacia 2019 - Bathco\" \/>\n<meta property=\"og:description\" content=\"A continuaci\u00f3n se hace un resumen de los hitos de la compa\u00f1\u00eda de estos 12 meses. Comenz\u00f3 lanzando el nuevo cat\u00e1logo Natural Series, un documento que presenta piezas con un dise\u00f1o muy cuidado y con el material como protagonista. En la feria de Cevisama que se celebr\u00f3 en febrero se presentaron nuevos productos totalmente novedosos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"677\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/\",\"name\":\"Bathco hace balance del 2018 para impulsarse hacia 2019 - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg\",\"datePublished\":\"2019-01-02T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg\",\"width\":677,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bathco hace balance del 2018 para impulsarse hacia 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bathco hace balance del 2018 para impulsarse hacia 2019 - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/","og_locale":"en_US","og_type":"article","og_title":"Bathco hace balance del 2018 para impulsarse hacia 2019 - Bathco","og_description":"A continuaci\u00f3n se hace un resumen de los hitos de la compa\u00f1\u00eda de estos 12 meses. Comenz\u00f3 lanzando el nuevo cat\u00e1logo Natural Series, un documento que presenta piezas con un dise\u00f1o muy cuidado y con el material como protagonista. En la feria de Cevisama que se celebr\u00f3 en febrero se presentaron nuevos productos totalmente novedosos [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:31+00:00","og_image":[{"width":677,"height":420,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/","url":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/","name":"Bathco hace balance del 2018 para impulsarse hacia 2019 - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg","datePublished":"2019-01-02T00:00:00+00:00","dateModified":"2025-10-30T12:39:31+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24676_es-bathco-coge-impulso-para-afrontar-el-2019-Real.jpg","width":677,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/bathco-hace-balance-del-2018-para-impulsarse-hacia-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Bathco hace balance del 2018 para impulsarse hacia 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14856"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14855"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}