{"id":14868,"date":"2019-02-04T00:00:00","date_gmt":"2019-02-04T00:00:00","guid":{"rendered":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/"},"modified":"2025-10-30T12:39:31","modified_gmt":"2025-10-30T12:39:31","slug":"lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019","status":"publish","type":"journal","link":"https:\/\/www.thebathcollection.com\/en\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/","title":{"rendered":"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019"},"content":{"rendered":"<p>La luz ya es algo cotidiano a lo que nos hemos acostumbrado por completo. Lo que era algo casi m\u00e1gico hace siglos, es una cuesti\u00f3n de lo m\u00e1s com\u00fan. Todos sabemos que con un simple gesto pasaremos en un segundo de la oscuridad total a un sinf\u00edn de formas y colores que tenemos frente a nosotros a diario.<\/p>\n<p>Teniendo en cuenta lo anterior, los artistas de Bathco Atelier quisieron resucitar esa capacidad de sorprender para ofrecer algo rompedor dirigido tanto a proyectos privados como a restaurantes o locales nocturnos.<\/p>\n<p>Los artistas de la compa\u00f1\u00eda c\u00e1ntabra han investigado durante meses con diferentes pigmentos y su reacci\u00f3n al calor sobre la porcelana. El resultado ha sido una serie de lavabos y murales decorados con calcas cer\u00e1micas o pintados a mano a los que se les aplica un pigmento fotolum\u00ednico que reacciona a la luz ultravioleta o luz negra.<\/p>\n<p>Esta nueva t\u00e9cnica ofrece la oportunidad de crear proyectos totalmente personalizados con el atractivo que aporta la luz ultravioleta.<\/p>\n<p><strong><a title=\"Lavabos y murales lum\u00ednicos\" href=\"https:\/\/youtu.be\/WH-BybqbtJM\">Ver v\u00eddeo en Youtube.<\/a><\/strong><\/p>\n<p><strong><br \/><\/strong><\/p>\n<p><a href=\"http:\/\/atelier.thebathcollection.com\/id\/\">Puedes ver la descripci\u00f3n de los lavabos en la web de Bathco Atelier.<\/a><\/p>","protected":false},"featured_media":14869,"parent":0,"template":"","journal_categories":[619],"class_list":["post-14868","journal","type-journal","status-publish","has-post-thumbnail","hentry","journal_categories-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019 - Bathco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thebathcollection.com\/en\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019 - Bathco\" \/>\n<meta property=\"og:description\" content=\"La luz ya es algo cotidiano a lo que nos hemos acostumbrado por completo. Lo que era algo casi m\u00e1gico hace siglos, es una cuesti\u00f3n de lo m\u00e1s com\u00fan. Todos sabemos que con un simple gesto pasaremos en un segundo de la oscuridad total a un sinf\u00edn de formas y colores que tenemos frente a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thebathcollection.com\/en\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Bathco\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1934\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/\",\"name\":\"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019 - Bathco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg\",\"datePublished\":\"2019-02-04T00:00:00+00:00\",\"dateModified\":\"2025-10-30T12:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thebathcollection.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg\",\"width\":1934,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journals\",\"item\":\"https:\\\/\\\/www.thebathcollection.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thebathcollection.com\\\/#website\",\"url\":\"https:\\\/\\\/www.thebathcollection.com\\\/\",\"name\":\"Bathco\",\"description\":\"Lavabos, sanitarios, platos de ducha y accesorios para el cuarto de ba\u00f1o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thebathcollection.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019 - Bathco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thebathcollection.com\/en\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/","og_locale":"en_US","og_type":"article","og_title":"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019 - Bathco","og_description":"La luz ya es algo cotidiano a lo que nos hemos acostumbrado por completo. Lo que era algo casi m\u00e1gico hace siglos, es una cuesti\u00f3n de lo m\u00e1s com\u00fan. Todos sabemos que con un simple gesto pasaremos en un segundo de la oscuridad total a un sinf\u00edn de formas y colores que tenemos frente a [&hellip;]","og_url":"https:\/\/www.thebathcollection.com\/en\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/","og_site_name":"Bathco","article_modified_time":"2025-10-30T12:39:31+00:00","og_image":[{"width":1934,"height":1200,"url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/","url":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/","name":"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019 - Bathco","isPartOf":{"@id":"https:\/\/www.thebathcollection.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg","datePublished":"2019-02-04T00:00:00+00:00","dateModified":"2025-10-30T12:39:31+00:00","breadcrumb":{"@id":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/#primaryimage","url":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg","contentUrl":"https:\/\/www.thebathcollection.com\/wp-content\/uploads\/2025\/10\/24734_es-lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019-Real.jpg","width":1934,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.thebathcollection.com\/journal\/lavabos-y-murales-luminicos-de-bathco-sorprenden-en-cevisama-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thebathcollection.com\/"},{"@type":"ListItem","position":2,"name":"Journals","item":"https:\/\/www.thebathcollection.com\/journal\/"},{"@type":"ListItem","position":3,"name":"Lavabos y murales lum\u00ednicos de Bathco sorprenden en Cevisama 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.thebathcollection.com\/#website","url":"https:\/\/www.thebathcollection.com\/","name":"Bathco","description":"Washbasins, toilets, shower trays and bathroom accessories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thebathcollection.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal\/14868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal"}],"about":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/types\/journal"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media\/14869"}],"wp:attachment":[{"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/media?parent=14868"}],"wp:term":[{"taxonomy":"journal_categories","embeddable":true,"href":"https:\/\/www.thebathcollection.com\/en\/wp-json\/wp\/v2\/journal_categories?post=14868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}